{"id":1865,"count":11,"description":"Apoye la salud digestiva de su mascota con nuestros nutrac\u00e9uticos para el apoyo gastrointestinal. Dise\u00f1ados para mantener un intestino equilibrado, una digesti\u00f3n normal y la absorci\u00f3n de nutrientes, estos suplementos ayudan a mantener el est\u00f3mago de su mascota feliz y saludable. Ya sea para tratar molestias ocasionales o para mascotas que necesitan apoyo continuo, nuestras f\u00f3rmulas respaldadas por la ciencia ofrecen soluciones suaves y naturales para un sistema digestivo saludable y un bienestar general.","link":"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/","name":"Gastrointestinal","slug":"gastrointestinal-es","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gastrointestinal - vetplus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastrointestinal - vetplus\" \/>\n<meta property=\"og:description\" content=\"Apoye la salud digestiva de su mascota con nuestros nutrac\u00e9uticos para el apoyo gastrointestinal. Dise\u00f1ados para mantener un intestino equilibrado, una digesti\u00f3n normal y la absorci\u00f3n de nutrientes, estos suplementos ayudan a mantener el est\u00f3mago de su mascota feliz y saludable. Ya sea para tratar molestias ocasionales o para mascotas que necesitan apoyo continuo, nuestras f\u00f3rmulas respaldadas por la ciencia ofrecen soluciones suaves y naturales para un sistema digestivo saludable y un bienestar general.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/\" \/>\n<meta property=\"og:site_name\" content=\"vetplus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@vetplusuk\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/product-category\\\/gastrointestinal-es\\\/\",\"url\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/product-category\\\/gastrointestinal-es\\\/\",\"name\":\"Gastrointestinal - vetplus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/product-category\\\/gastrointestinal-es\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/product-category\\\/gastrointestinal-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gastrointestinal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/\",\"name\":\"vetplus\",\"description\":\"The Global Leader in Veterinary Nutraceuticals\",\"publisher\":{\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/#organization\",\"name\":\"VetPlus\",\"url\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vetplusglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Group-955-1.jpg\",\"contentUrl\":\"https:\\\/\\\/vetplusglobal.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Group-955-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"VetPlus\"},\"image\":{\"@id\":\"https:\\\/\\\/vetplusglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/vetplusUK\\\/\",\"https:\\\/\\\/x.com\\\/vetplusuk\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastrointestinal - vetplus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/","og_locale":"es_ES","og_type":"article","og_title":"Gastrointestinal - vetplus","og_description":"Apoye la salud digestiva de su mascota con nuestros nutrac\u00e9uticos para el apoyo gastrointestinal. Dise\u00f1ados para mantener un intestino equilibrado, una digesti\u00f3n normal y la absorci\u00f3n de nutrientes, estos suplementos ayudan a mantener el est\u00f3mago de su mascota feliz y saludable. Ya sea para tratar molestias ocasionales o para mascotas que necesitan apoyo continuo, nuestras f\u00f3rmulas respaldadas por la ciencia ofrecen soluciones suaves y naturales para un sistema digestivo saludable y un bienestar general.","og_url":"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/","og_site_name":"vetplus","twitter_card":"summary_large_image","twitter_site":"@vetplusuk","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/","url":"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/","name":"Gastrointestinal - vetplus","isPartOf":{"@id":"https:\/\/vetplusglobal.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/#breadcrumb"},"inLanguage":"es-ES"},{"@type":"BreadcrumbList","@id":"https:\/\/vetplusglobal.com\/es\/product-category\/gastrointestinal-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vetplusglobal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gastrointestinal"}]},{"@type":"WebSite","@id":"https:\/\/vetplusglobal.com\/es\/#website","url":"https:\/\/vetplusglobal.com\/es\/","name":"vetplus","description":"The Global Leader in Veterinary Nutraceuticals","publisher":{"@id":"https:\/\/vetplusglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vetplusglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/vetplusglobal.com\/es\/#organization","name":"VetPlus","url":"https:\/\/vetplusglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/vetplusglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/vetplusglobal.com\/wp-content\/uploads\/2024\/12\/Group-955-1.jpg","contentUrl":"https:\/\/vetplusglobal.com\/wp-content\/uploads\/2024\/12\/Group-955-1.jpg","width":696,"height":696,"caption":"VetPlus"},"image":{"@id":"https:\/\/vetplusglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vetplusUK\/","https:\/\/x.com\/vetplusuk"]}]}},"_links":{"self":[{"href":"https:\/\/vetplusglobal.com\/es\/wp-json\/wp\/v2\/product_cat\/1865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vetplusglobal.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/vetplusglobal.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/vetplusglobal.com\/es\/wp-json\/wp\/v2\/product?product_cat=1865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}